{"id":15715,"date":"2025-02-28T22:25:27","date_gmt":"2025-02-28T22:25:27","guid":{"rendered":"https:\/\/kk26.dieservices.de\/?post_type=portfolio_item&#038;p=15715"},"modified":"2025-10-28T00:26:24","modified_gmt":"2025-10-28T00:26:24","slug":"trp_language-languagede_de-27-mai-2024-konzert-in-memoriam-peter-eoetvoes-trp_language-trp_language-languageen_gb-may-27-2024-concert-in-memoriam-of-peter-eoetvoes-trp_language","status":"publish","type":"portfolio_item","link":"https:\/\/kk26.dieservices.de\/en\/subject\/trp_language-languagede_de-27-mai-2024-konzert-in-memoriam-peter-eoetvoes-trp_language-trp_language-languageen_gb-may-27-2024-concert-in-memoriam-of-peter-eoetvoes-trp_language\/","title":{"rendered":"27. Mai 2024: Konzert mit Ensemble Modern in memoriam P\u00c9TER E\u00d6TV\u00d6S"},"content":{"rendered":"<p><noscript><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-15723\" src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-800x770.jpg\" alt width=\"823\" height=\"792\" srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-800x770.jpg 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-1024x986.jpg 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-768x739.jpg 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-1536x1479.jpg 1536w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-2048x1972.jpg 2048w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-12x12.jpg 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-24x24.jpg 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-2000x1925.jpg 2000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-1000x963.jpg 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-1800x1733.jpg 1800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-582x560.jpg 582w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-600x578.jpg 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-1200x1155.jpg 1200w\" sizes=\"(max-width: 823px) 100vw, 823px\"><\/noscript><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-15723 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20823%20792%22%3E%3C%2Fsvg%3E\" alt width=\"823\" height=\"792\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20823%20792%22%3E%3C%2Fsvg%3E 823w\" sizes=\"(max-width: 823px) 100vw, 823px\" data-srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-800x770.jpg 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-1024x986.jpg 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-768x739.jpg 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-1536x1479.jpg 1536w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-2048x1972.jpg 2048w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-12x12.jpg 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-24x24.jpg 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-2000x1925.jpg 2000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-1000x963.jpg 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-1800x1733.jpg 1800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-582x560.jpg 582w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-600x578.jpg 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-1200x1155.jpg 1200w\" data-src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/drache_262cover-800x770.jpg\"><\/p>\n\n<p> Together with <strong>Ensemble Modern<\/strong>, I performed the <strong>monologue of the The little Chinese, &#8222;Heimkehr&#8220; &nbsp;<\/strong> from <strong>P\u00e9ter E\u00f6tv\u00f6s\u2019 The GOLDEN DRAGON<\/strong>&nbsp;at the Alte Oper. Singing this music again ten years after the world premiere was a particularly moving moment for me\u2014 a journey through time, filled with memories and deeply felt emotion. <noscript><img decoding=\"async\" class=\"alignnone size-medium wp-image-15721\" src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-800x533.jpg\" alt width=\"800\" height=\"533\" srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-800x533.jpg 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-1024x683.jpg 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-768x512.jpg 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-18x12.jpg 18w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-24x16.jpg 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-1000x667.jpg 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-840x560.jpg 840w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-600x400.jpg 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/noscript><img decoding=\"async\" class=\"alignnone size-medium wp-image-15721 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20533%22%3E%3C%2Fsvg%3E\" alt width=\"800\" height=\"533\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20533%22%3E%3C%2Fsvg%3E 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" data-srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-800x533.jpg 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-1024x683.jpg 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-768x512.jpg 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-18x12.jpg 18w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-24x16.jpg 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-1000x667.jpg 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-840x560.jpg 840w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-600x400.jpg 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348.jpg 1080w\" data-src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Ins_1991710348-800x533.jpg\"><\/p>\n<p><strong>P. E\u00f6tv\u00f6s \u201eDer Goldene Drache\u201c (Oper Frankfurt, 2014 \u2013 Fotos: Monika Rittershaus<\/strong><\/p>\n<p><noscript><img decoding=\"async\" class=\"alignnone size-medium wp-image-15727\" src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-800x800.png\" alt width=\"800\" height=\"800\" srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/noscript><img decoding=\"async\" class=\"alignnone size-medium wp-image-15727 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20800%22%3E%3C%2Fsvg%3E\" alt width=\"800\" height=\"800\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20800%22%3E%3C%2Fsvg%3E 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" data-srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4.png 1080w\" data-src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/4-800x800.png\"> <noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15728\" src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-800x800.png\" alt width=\"800\" height=\"800\" srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15728 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20800%22%3E%3C%2Fsvg%3E\" alt width=\"800\" height=\"800\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20800%22%3E%3C%2Fsvg%3E 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" data-srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5.png 1080w\" data-src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/5-800x800.png\"> <noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15729\" src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-800x800.png\" alt width=\"800\" height=\"800\" srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15729 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20800%22%3E%3C%2Fsvg%3E\" alt width=\"800\" height=\"800\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20800%22%3E%3C%2Fsvg%3E 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" data-srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6.png 1080w\" data-src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/6-800x800.png\"> <noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15730\" src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-800x800.png\" alt width=\"800\" height=\"800\" srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15730 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20800%22%3E%3C%2Fsvg%3E\" alt width=\"800\" height=\"800\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20800%22%3E%3C%2Fsvg%3E 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" data-srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7.png 1080w\" data-src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/7-800x800.png\"> <noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15731\" src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-800x800.png\" alt width=\"800\" height=\"800\" srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15731 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20800%22%3E%3C%2Fsvg%3E\" alt width=\"800\" height=\"800\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20800%22%3E%3C%2Fsvg%3E 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" data-srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8.png 1080w\" data-src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/8-800x800.png\"> <noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15732\" src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-800x800.png\" alt width=\"800\" height=\"800\" srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15732 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20800%22%3E%3C%2Fsvg%3E\" alt width=\"800\" height=\"800\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20800%22%3E%3C%2Fsvg%3E 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" data-srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9.png 1080w\" data-src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/9-800x800.png\"><\/p>\n<p><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-15722\" src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Eoetvoes_Drache_OperFrankfur_04.jpg\" alt width=\"802\" height=\"534\" srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Eoetvoes_Drache_OperFrankfur_04.jpg 778w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Eoetvoes_Drache_OperFrankfur_04-768x511.jpg 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Eoetvoes_Drache_OperFrankfur_04-18x12.jpg 18w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Eoetvoes_Drache_OperFrankfur_04-24x16.jpg 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Eoetvoes_Drache_OperFrankfur_04-600x399.jpg 600w\" sizes=\"(max-width: 802px) 100vw, 802px\"><\/noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-15722 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20802%20534%22%3E%3C%2Fsvg%3E\" alt width=\"802\" height=\"534\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20802%20534%22%3E%3C%2Fsvg%3E 802w\" sizes=\"(max-width: 802px) 100vw, 802px\" data-srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Eoetvoes_Drache_OperFrankfur_04.jpg 778w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Eoetvoes_Drache_OperFrankfur_04-768x511.jpg 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Eoetvoes_Drache_OperFrankfur_04-18x12.jpg 18w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Eoetvoes_Drache_OperFrankfur_04-24x16.jpg 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Eoetvoes_Drache_OperFrankfur_04-600x399.jpg 600w\" data-src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Eoetvoes_Drache_OperFrankfur_04.jpg\"><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15735\" src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-800x800.png\" alt width=\"800\" height=\"800\" srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15735 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20800%22%3E%3C%2Fsvg%3E\" alt width=\"800\" height=\"800\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20800%20800%22%3E%3C%2Fsvg%3E 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" data-srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen.png 1080w\" data-src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/Peter-Eoetvoes-Fuer-den-ersten-Jungen-mit-den-Zahnschmerzen-800x800.png\"><\/p>","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15734\" src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-800x800.png\" alt=\"\" width=\"800\" height=\"800\" srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-800x800.png 800w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-1024x1024.png 1024w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-400x400.png 400w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-768x768.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-12x12.png 12w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-24x24.png 24w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-1000x1000.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-280x280.png 280w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-560x560.png 560w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-600x600.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p> Together with <strong>Ensemble Modern<\/strong>, I performed the <strong>monologue of the The little Chinese, &#8222;Heimkehr&#8220; \u00a0<\/strong> from <strong>P\u00e9ter E\u00f6tv\u00f6s\u2019 The GOLDEN DRAGON<\/strong>\u00a0at the Alte Oper. Singing this music again ten years after the world premiere was a particularly moving moment for me\u2014 a journey through time, filled with memories and deeply felt emotion. <\/p>","protected":false},"author":3,"featured_media":15734,"template":"","meta":{"_wpzb_portfolio_video_type":"","_wpzb_portfolio_video_id":0,"_wpzb_portfolio_video_url":"","footnotes":""},"portfolio":[352,391],"class_list":["post-15715","portfolio_item","type-portfolio_item","status-publish","has-post-thumbnail","hentry","portfolio-news-normal","portfolio-news-normal-startseite"],"featured_media_urls":{"thumbnail":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-400x400.png",400,400,true],"medium":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-800x800.png",800,800,true],"medium_large":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-768x768.png",768,768,true],"large":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-1024x1024.png",930,930,true],"1536x1536":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1.png",1080,1080,false],"2048x2048":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1.png",1080,1080,false],"trp-custom-language-flag":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-12x12.png",12,12,true],"downloadlist-icon-custom":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-24x24.png",24,24,true],"featured":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1.png",1080,1080,false],"featured@2x":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1.png",1080,1080,false],"featured-small":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-1000x1000.png",1000,1000,true],"recent-thumbnail":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-345x192.png",345,192,true],"recent-thumbnail-retina":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-690x384.png",690,384,true],"woo-featured":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-280x280.png",280,280,true],"entry-cover":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1.png",1080,1080,false],"entry-cover@2x":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1.png",1080,1080,false],"loop":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-950x320.png",950,320,true],"loop@2x":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1.png",640,640,false],"portfolio-scroller-widget":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-560x560.png",560,560,true],"portfolio_item-thumbnail":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-600x400.png",600,400,true],"portfolio_item-thumbnail@2x":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-1080x800.png",1080,800,true],"portfolio_item-masonry":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-600x600.png",600,600,true],"portfolio_item-thumbnail_wide":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-1080x600.png",1080,600,true],"portfolio_item-thumbnail_wide_cinema":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-1080x750.png",1080,750,true],"portfolio_item-thumbnail_cinema":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-800x335.png",800,335,true],"portfolio_item-thumbnail_portrait":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-600x900.png",600,900,true],"portfolio_item-thumbnail_square":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1-800x800.png",800,800,true],"portfolio_item-masonry@2x":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1.png",1080,1080,false],"portfolio_item-thumbnail_portrait@2x":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/02\/1.png",1080,1080,false]},"_links":{"self":[{"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/portfolio_item\/15715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/portfolio_item"}],"about":[{"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/types\/portfolio_item"}],"author":[{"embeddable":true,"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":7,"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/portfolio_item\/15715\/revisions"}],"predecessor-version":[{"id":18239,"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/portfolio_item\/15715\/revisions\/18239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/media\/15734"}],"wp:attachment":[{"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/media?parent=15715"}],"wp:term":[{"taxonomy":"portfolio","embeddable":true,"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/portfolio?post=15715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}