{"id":15885,"date":"2025-03-02T01:41:00","date_gmt":"2025-03-02T01:41:00","guid":{"rendered":"https:\/\/kk26.dieservices.de\/?post_type=portfolio_item&#038;p=15885"},"modified":"2025-08-19T11:31:13","modified_gmt":"2025-08-19T11:31:13","slug":"trp_language-languagede_de-niederlaendische-erstauffuehrung-von-mysliveceks-abramo-ed-isacco-im-concertgebouw-amsterdam-trp_language-trp_language-languageen_gb-dutch-premiere-of-m","status":"publish","type":"portfolio_item","link":"https:\/\/kk26.dieservices.de\/en\/subject\/trp_language-languagede_de-niederlaendische-erstauffuehrung-von-mysliveceks-abramo-ed-isacco-im-concertgebouw-amsterdam-trp_language-trp_language-languageen_gb-dutch-premiere-of-m\/","title":{"rendered":"PRESSE Myslive\u010deks &#8222;Abramo ed Isacco&#8220; im Concertgebouw Amsterdam"},"content":{"rendered":"<br>\n\n<p><noscript><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-16071\" src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-640x800.png\" alt width=\"640\" height=\"800\" srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-640x800.png 640w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-819x1024.png 819w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-768x960.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-10x12.png 10w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-19x24.png 19w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-1000x1250.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-448x560.png 448w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-600x750.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2.png 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\"><\/noscript><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-16071 lazyload\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20640%20800%22%3E%3C%2Fsvg%3E\" alt width=\"640\" height=\"800\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20viewBox%3D%220%200%20640%20800%22%3E%3C%2Fsvg%3E 640w\" sizes=\"(max-width: 640px) 100vw, 640px\" data-srcset=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-640x800.png 640w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-819x1024.png 819w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-768x960.png 768w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-10x12.png 10w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-19x24.png 19w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-1000x1250.png 1000w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-448x560.png 448w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-600x750.png 600w, https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2.png 1080w\" data-src=\"https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-640x800.png\"><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>","protected":false},"author":3,"featured_media":16071,"template":"","meta":{"_wpzb_portfolio_video_type":"","_wpzb_portfolio_video_id":0,"_wpzb_portfolio_video_url":"","footnotes":""},"portfolio":[352,391],"class_list":["post-15885","portfolio_item","type-portfolio_item","status-publish","has-post-thumbnail","hentry","portfolio-news-normal","portfolio-news-normal-startseite"],"featured_media_urls":{"thumbnail":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-400x400.png",400,400,true],"medium":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-640x800.png",640,800,true],"medium_large":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-768x960.png",768,960,true],"large":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-819x1024.png",819,1024,true],"1536x1536":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2.png",1080,1350,false],"2048x2048":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2.png",1080,1350,false],"trp-custom-language-flag":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-10x12.png",10,12,true],"downloadlist-icon-custom":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-19x24.png",19,24,true],"featured":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2.png",1080,1350,false],"featured@2x":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2.png",1080,1350,false],"featured-small":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-1000x1250.png",1000,1250,true],"recent-thumbnail":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-345x192.png",345,192,true],"recent-thumbnail-retina":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-690x384.png",690,384,true],"woo-featured":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-280x280.png",280,280,true],"entry-cover":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2.png",1080,1350,false],"entry-cover@2x":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2.png",1080,1350,false],"loop":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-950x320.png",950,320,true],"loop@2x":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2.png",512,640,false],"portfolio-scroller-widget":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-448x560.png",448,560,true],"portfolio_item-thumbnail":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-600x400.png",600,400,true],"portfolio_item-thumbnail@2x":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-1080x800.png",1080,800,true],"portfolio_item-masonry":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-600x750.png",600,750,true],"portfolio_item-thumbnail_wide":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-1080x600.png",1080,600,true],"portfolio_item-thumbnail_wide_cinema":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-1080x750.png",1080,750,true],"portfolio_item-thumbnail_cinema":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-800x335.png",800,335,true],"portfolio_item-thumbnail_portrait":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-600x900.png",600,900,true],"portfolio_item-thumbnail_square":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2-800x800.png",800,800,true],"portfolio_item-masonry@2x":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2.png",1080,1350,false],"portfolio_item-thumbnail_portrait@2x":["https:\/\/kk26.dieservices.de\/wp-content\/uploads\/2025\/03\/2-2.png",1080,1350,false]},"_links":{"self":[{"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/portfolio_item\/15885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/portfolio_item"}],"about":[{"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/types\/portfolio_item"}],"author":[{"embeddable":true,"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/portfolio_item\/15885\/revisions"}],"predecessor-version":[{"id":16448,"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/portfolio_item\/15885\/revisions\/16448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/media\/16071"}],"wp:attachment":[{"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/media?parent=15885"}],"wp:term":[{"taxonomy":"portfolio","embeddable":true,"href":"https:\/\/kk26.dieservices.de\/en\/wp-json\/wp\/v2\/portfolio?post=15885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}